{"id":9871,"date":"2026-01-12T10:26:02","date_gmt":"2026-01-12T10:26:02","guid":{"rendered":"https:\/\/dxdev.site\/induquimica\/?p=9871"},"modified":"2026-01-12T10:27:33","modified_gmt":"2026-01-12T10:27:33","slug":"provas-em-substratos-de-embalagem-filmproof-na-abc-packmedia","status":"publish","type":"post","link":"https:\/\/dxdev.site\/induquimica\/provas-em-substratos-de-embalagem-filmproof-na-abc-packmedia\/","title":{"rendered":"Provas em substratos de embalagem &#8211; Filmproof na abc packmedia"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"9871\" class=\"elementor elementor-9871\" data-elementor-settings=\"{&quot;ha_cmc_init_switcher&quot;:&quot;no&quot;}\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-112dc5c e-flex e-con-boxed e-con e-parent\" data-id=\"112dc5c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-85b7073 elementor-widget elementor-widget-image\" data-id=\"85b7073\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"104\" src=\"https:\/\/dxdev.site\/induquimica\/wp-content\/uploads\/2023\/07\/GMG_Logo-01-300x104-1.png\" class=\"attachment-large size-large wp-image-4136\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-100dbe4 elementor-widget elementor-widget-image\" data-id=\"100dbe4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"241\" src=\"https:\/\/dxdev.site\/induquimica\/wp-content\/uploads\/2026\/01\/solutions-abcpackmedia-header-landscape-1-1024x308.jpg\" class=\"attachment-large size-large wp-image-9872\" alt=\"\" srcset=\"https:\/\/dxdev.site\/induquimica\/wp-content\/uploads\/2026\/01\/solutions-abcpackmedia-header-landscape-1-1024x308.jpg 1024w, https:\/\/dxdev.site\/induquimica\/wp-content\/uploads\/2026\/01\/solutions-abcpackmedia-header-landscape-1-300x90.jpg 300w, https:\/\/dxdev.site\/induquimica\/wp-content\/uploads\/2026\/01\/solutions-abcpackmedia-header-landscape-1-768x231.jpg 768w, https:\/\/dxdev.site\/induquimica\/wp-content\/uploads\/2026\/01\/solutions-abcpackmedia-header-landscape-1-1536x461.jpg 1536w, https:\/\/dxdev.site\/induquimica\/wp-content\/uploads\/2026\/01\/solutions-abcpackmedia-header-landscape-1.jpg 1928w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33fa2d7 elementor-widget elementor-widget-text-editor\" data-id=\"33fa2d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"72\" data-end=\"225\">\u201cA qualidade colorim\u00e9trica \u00e9 convincente e permite-nos oferecer a mesma flexibilidade e rapidez em diferentes tipos de filme que j\u00e1 oferecemos em papel.\u201d<\/p><p data-start=\"227\" data-end=\"308\"><em data-start=\"227\" data-end=\"308\">Eva J\u00fcde-L\u00f6ffler, respons\u00e1vel pela gest\u00e3o de cor no LEADStudio da abc packmedia<\/em><\/p><h3 data-start=\"311\" data-end=\"326\">O Desafio<\/h3><p data-start=\"327\" data-end=\"387\"><strong data-start=\"327\" data-end=\"387\">Provas com precis\u00e3o crom\u00e1tica em substratos de embalagem<\/strong><\/p><p data-start=\"389\" data-end=\"856\">Muitos clientes da abc packmedia n\u00e3o pretendem apenas provas para comunicar o resultado de cor em papel, mas tamb\u00e9m em diferentes substratos de embalagem. Em particular, o processo de produ\u00e7\u00e3o de provas em filme, atrav\u00e9s de lamina\u00e7\u00e3o e de um sistema de provas baseado em laser, \u00e9 bastante complexo.<br data-start=\"687\" data-end=\"690\" \/>Como n\u00e3o \u00e9 poss\u00edvel utilizar diretamente os perfis de cor GMG existentes neste processo, estes t\u00eam primeiro de ser convertidos para outra tecnologia de gest\u00e3o de cor.<\/p><p data-start=\"858\" data-end=\"1029\">Procurava-se uma solu\u00e7\u00e3o que se integrasse no sistema GMG j\u00e1 existente, que permitisse converter os perfis de cor de forma r\u00e1pida e precisa e que fosse f\u00e1cil de controlar.<\/p><h3 data-start=\"1032\" data-end=\"1047\">A Solu\u00e7\u00e3o<\/h3><p data-start=\"1048\" data-end=\"1099\"><strong data-start=\"1048\" data-end=\"1099\">Gest\u00e3o de Cor GMG para a Epson SureColor S80600<\/strong><\/p><p data-start=\"1101\" data-end=\"1338\">A impressora de jato de tinta <strong data-start=\"1131\" data-end=\"1150\">Epson SC-S80600<\/strong> permite \u00e0 abc packmedia criar, de forma r\u00e1pida e simples, provas em filme e prot\u00f3tipos de embalagem com elevada precis\u00e3o crom\u00e1tica. O sistema \u00e9 controlado atrav\u00e9s do <strong data-start=\"1317\" data-end=\"1335\">GMG ColorProof<\/strong>.<\/p><p data-start=\"1340\" data-end=\"1640\">Os projetos existentes no <strong data-start=\"1366\" data-end=\"1383\">GMG OpenColor<\/strong> e os perfis de cor GMG j\u00e1 dispon\u00edveis podem ser convertidos de forma r\u00e1pida e f\u00e1cil para os diferentes substratos. A impressora pode ser recalibrada dentro de toler\u00e2ncias muito rigorosas, garantindo um desempenho consistente e uma reprodu\u00e7\u00e3o de cor fi\u00e1vel.<\/p><h3 data-start=\"1643\" data-end=\"1662\">Os Benef\u00edcios<\/h3><ul data-start=\"1663\" data-end=\"2041\"><li data-start=\"1663\" data-end=\"1722\"><p data-start=\"1665\" data-end=\"1722\">Maior flexibilidade na comunica\u00e7\u00e3o de cor com o cliente<\/p><\/li><li data-start=\"1723\" data-end=\"1810\"><p data-start=\"1725\" data-end=\"1810\">Excelente correspond\u00eancia de cor entre a prova standard em papel e a prova em filme<\/p><\/li><li data-start=\"1811\" data-end=\"1880\"><p data-start=\"1813\" data-end=\"1880\">Aumento da produtividade atrav\u00e9s da redu\u00e7\u00e3o do tempo de convers\u00e3o<\/p><\/li><li data-start=\"1881\" data-end=\"1938\"><p data-start=\"1883\" data-end=\"1938\">Controlo simples e integra\u00e7\u00e3o perfeita no sistema GMG<\/p><\/li><li data-start=\"1939\" data-end=\"2041\"><p data-start=\"1941\" data-end=\"2041\">Expans\u00e3o r\u00e1pida do portef\u00f3lio com novos suportes, utilizando o <strong data-start=\"2004\" data-end=\"2039\">GMG Calibration Creation Wizard<\/strong><\/p><\/li><\/ul><p data-start=\"2044\" data-end=\"2086\"><a href=\"https:\/\/gmgcolor.com\/fileadmin\/Solutions\/PDF_Solutions\/GMG-Case-Study-ABC-Packmedia-EN.pdf\" target=\"_blank\" rel=\"noopener nofollow\"><strong data-start=\"2044\" data-end=\"2086\">Leia o caso de sucesso completo aqui &gt;<\/strong><\/a><\/p><h3 data-start=\"2089\" data-end=\"2108\">abc packmedia<\/h3><p data-start=\"2110\" data-end=\"2435\">H\u00e1 mais de 40 anos que o nome abc packmedia \u00e9 sin\u00f3nimo de um servi\u00e7o completo e fi\u00e1vel na pr\u00e9-impress\u00e3o de embalagens em toda a Europa. Fabricantes de marcas reconhecidas, bem como in\u00fameras ag\u00eancias de design e gr\u00e1ficas de embalagens, confiam no prestador de servi\u00e7os sediado em Hamburgo quando se trata de elevada qualidade.<\/p><p data-start=\"2438\" data-end=\"2532\"><strong data-start=\"2438\" data-end=\"2469\">abc packmedia GmbH &amp; Co. KG<\/strong><br data-start=\"2469\" data-end=\"2472\" \/>Conventstra\u00dfe 1\u20133<br data-start=\"2489\" data-end=\"2492\" \/>22089 Hamburgo<br data-start=\"2506\" data-end=\"2509\" \/><a class=\"decorated-link\" href=\"http:\/\/www.abc-packmedia.com\" target=\"_new\" rel=\"noopener nofollow\" data-start=\"2509\" data-end=\"2530\">www.abc-packmedia.com<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u201cA qualidade colorim\u00e9trica \u00e9 convincente e permite-nos oferecer a mesma flexibilidade e rapidez em diferentes tipos de filme que j\u00e1 oferecemos em papel.\u201d Eva J\u00fcde-L\u00f6ffler, respons\u00e1vel pela gest\u00e3o de cor no LEADStudio da abc packmedia O Desafio Provas com precis\u00e3o crom\u00e1tica em substratos de embalagem Muitos clientes da abc packmedia n\u00e3o pretendem apenas provas para [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":9872,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_sitemap_exclude":false,"_sitemap_priority":"","_sitemap_frequency":"","_joinchat":[],"footnotes":""},"categories":[25,50],"tags":[],"class_list":["post-9871","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-case-studies","category-gmg-case-studies"],"_links":{"self":[{"href":"https:\/\/dxdev.site\/induquimica\/wp-json\/wp\/v2\/posts\/9871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dxdev.site\/induquimica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dxdev.site\/induquimica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dxdev.site\/induquimica\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/dxdev.site\/induquimica\/wp-json\/wp\/v2\/comments?post=9871"}],"version-history":[{"count":0,"href":"https:\/\/dxdev.site\/induquimica\/wp-json\/wp\/v2\/posts\/9871\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dxdev.site\/induquimica\/wp-json\/wp\/v2\/media\/9872"}],"wp:attachment":[{"href":"https:\/\/dxdev.site\/induquimica\/wp-json\/wp\/v2\/media?parent=9871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dxdev.site\/induquimica\/wp-json\/wp\/v2\/categories?post=9871"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dxdev.site\/induquimica\/wp-json\/wp\/v2\/tags?post=9871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}