{"id":9364,"date":"2025-11-13T11:50:06","date_gmt":"2025-11-13T11:50:06","guid":{"rendered":"https:\/\/dxdev.site\/induquimica\/?p=9364"},"modified":"2025-11-13T11:50:08","modified_gmt":"2025-11-13T11:50:08","slug":"a-imprimerie-ste-julie-usa-a-solucao-crystal-da-esko-para-aumentar-a-agilidade-e-produzir-chapas-maiores-com-melhor-qualidade-em-menos-tempo","status":"publish","type":"post","link":"https:\/\/dxdev.site\/induquimica\/a-imprimerie-ste-julie-usa-a-solucao-crystal-da-esko-para-aumentar-a-agilidade-e-produzir-chapas-maiores-com-melhor-qualidade-em-menos-tempo\/","title":{"rendered":"A Imprimerie Ste-Julie usa a solu\u00e7\u00e3o Crystal da Esko para aumentar a agilidade e produzir chapas maiores com melhor qualidade, em menos tempo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A Imprimerie Ste-Julie, empresa canadense l\u00edder do mercado de embalagens e etiquetas, procurava alavancar a produ\u00e7\u00e3o de chapas sem comprometer a qualidade da impress\u00e3o final. Com a necessidade de entregar chapas maiores em prazos reduzidos, a empresa identificou a Esko como a parceira perfeita para ajud\u00e1-los!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>O desafio: <\/strong>Velocidade, precis\u00e3o e qualidade <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>A solu\u00e7\u00e3o: <\/strong>Sistema de grava\u00e7\u00e3o de chapas Crystal da Esko <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Os benef\u00edcios: <\/strong>Velocidade, precis\u00e3o e qualidade<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">O cliente<\/h2>\n\n\n\n<h4 class=\"wp-block-heading\">Imprimerie Ste-Julie, Quebec, Canada<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">A\u00a0<a href=\"https:\/\/impsj.com\/en\" rel=\"nofollow noopener\" target=\"_blank\">Imprimerie Ste-Julie<\/a>\u00a0tem definido padr\u00f5es no setor de impress\u00e3o de etiqueta e filme termoencolh\u00edvel h\u00e1 mais de 40 anos. Fundada em 1975 em Quebec, Canad\u00e1, a Imprimerie Ste-Julie lidera e est\u00e1 sempre inovando para oferecer diferentes op\u00e7\u00f5es de impress\u00e3o aos seus clientes atendendo as necessidades relacionadas \u00e0 embalagem. Atualmente, a empresa tem mais de 120 funcion\u00e1rios e possui equipamento de \u00faltima gera\u00e7\u00e3o para fabrica\u00e7\u00e3o de etiquetas autoadesivas, filmes termoencolh\u00edveis, sacolas e etiquetas informativas, tanto na impress\u00e3o flexogr\u00e1fica como na digital, e uma variedade de acabamentos com valor agregado.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"667\" src=\"https:\/\/dxdev.site\/induquimica\/wp-content\/uploads\/2025\/11\/imprimerie-ste-julie_1-1.jpg\" alt=\"\" class=\"wp-image-9368\" srcset=\"https:\/\/dxdev.site\/induquimica\/wp-content\/uploads\/2025\/11\/imprimerie-ste-julie_1-1.jpg 1000w, https:\/\/dxdev.site\/induquimica\/wp-content\/uploads\/2025\/11\/imprimerie-ste-julie_1-1-300x200.jpg 300w, https:\/\/dxdev.site\/induquimica\/wp-content\/uploads\/2025\/11\/imprimerie-ste-julie_1-1-768x512.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/dxdev.site\/induquimica\/wp-content\/uploads\/2025\/11\/imprimerie-ste-julie_2-1-1024x512.jpg\" alt=\"\" class=\"wp-image-9370\" srcset=\"https:\/\/dxdev.site\/induquimica\/wp-content\/uploads\/2025\/11\/imprimerie-ste-julie_2-1-1024x512.jpg 1024w, https:\/\/dxdev.site\/induquimica\/wp-content\/uploads\/2025\/11\/imprimerie-ste-julie_2-1-300x150.jpg 300w, https:\/\/dxdev.site\/induquimica\/wp-content\/uploads\/2025\/11\/imprimerie-ste-julie_2-1-768x384.jpg 768w, https:\/\/dxdev.site\/induquimica\/wp-content\/uploads\/2025\/11\/imprimerie-ste-julie_2-1.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Com clientes em todo o Canad\u00e1, a Imprimerie Ste-Julie atende diversos setores do mercados, do aliment\u00edcio e farmac\u00eautico ao de produtos cosm\u00e9ticos e bebidas alco\u00f3licas. A empresa criou a reputa\u00e7\u00e3o de fazer a entrega visando seus quatro valores corporativos, assegurando que cada projeto seja executado com paix\u00e3o, qualidade, foco no cliente e agilidade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os clientes escolhem a Imprimerie Ste-Julie pela qualidade dos seus produtos, velocidade de execu\u00e7\u00e3o e compromisso com o servi\u00e7o de atendimento ao cliente, ao mesmo tempo que a variedade de op\u00e7\u00f5es que ela oferece posiciona a empresa entre as l\u00edderes do setor.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"challenge\">O desafio<\/h3>\n\n\n\n<h4 class=\"wp-block-heading\">Velocidade, precis\u00e3o e qualidade<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cA concorr\u00eancia sempre foi e ser\u00e1 forte em termos de qualidade e prazos de produ\u00e7\u00e3o,\u201d disse Simon Dumais, gerente de pr\u00e9-impress\u00e3o da Imprimerie Ste-Julie. \u201cNosso maior desafio \u00e9 manter sempre a qualidade da nossa impress\u00e3o e, ao mesmo tempo, garantir que a velocidade da produ\u00e7\u00e3o atenda \u00e0 demanda do mercado.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cPrecis\u00e1vamos produzir chapas maiores diariamente e percebemos que nossas antigas m\u00e1quinas e instala\u00e7\u00f5es de software eram um obst\u00e1culo para conseguirmos isso. Escolhemos a Esko como nossa parceira empresarial porque sabemos que ela oferece a mais completa variedade de produtos para atender \u00e0s nossas necessidades. Isso nos permitiu oferecer op\u00e7\u00f5es completas e um servi\u00e7o otimizado, o que \u00e9 muito importante para n\u00f3s. Al\u00e9m disso, a Esko oferece uma solu\u00e7\u00e3o para a automa\u00e7\u00e3o dos nossos processos de pr\u00e9-impress\u00e3o, algo essencial para atendermos \u00e0s expectativas de qualidade e velocidade do mercado atual.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c\u00c9 importante podermos padronizar e automatizar nossas opera\u00e7\u00f5es para evitar erros nos arquivos ou na etapa de produ\u00e7\u00e3o,\u201d acrescentou Simon. \u201cPor fim, quer\u00edamos garantir que tudo estaria interconectado para evitarmos erros no gerenciamento de dados. Esse n\u00edvel de conectividade automatizada permite economizar um tempo precioso que podemos usar para oferecer um servi\u00e7o mais focado no cliente.\u201d<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201cUsamos nosso sistema v\u00e1rias vezes ao dia, e agora ele \u00e9 parte essencial do nosso processo de produ\u00e7\u00e3o\u201d.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Simon Dumais, gerente de pr\u00e9-impress\u00e3o da Imprimerie Ste-Julie<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"solution\">A solu\u00e7\u00e3o<\/h3>\n\n\n\n<h4 class=\"wp-block-heading\">Sistema de grava\u00e7\u00e3o de chapas Crystal da Esko<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">A Imprimerie Ste-Julie produz, internamente, as pr\u00f3prias chapas flexogr\u00e1ficas, desde 2007, beneficiando-se dos custos de produ\u00e7\u00e3o e ganhos na efici\u00eancia com a maior velocidade de produ\u00e7\u00e3o. A solu\u00e7\u00e3o integrada de imagem e exposi\u00e7\u00e3o&nbsp;<a href=\"https:\/\/www.esko.com\/pt\/products\/cdi-crystal-xps\" rel=\"nofollow noopener\" target=\"_blank\">CDI Crystal XPS<\/a>, da Esko, foi instalada em setembro de 2019 no departamento de artes gr\u00e1ficas, onde 13 funcion\u00e1rios especializados trabalham nos processos de design gr\u00e1fico e pr\u00e9-impress\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A combina\u00e7\u00e3o de uma gravadora flexogr\u00e1fica CDI Crystal com uma expositora XPS Crystal proporciona um fluxo de trabalho de grava\u00e7\u00e3o de chapas flexogr\u00e1ficas perfeitamente integrado. Com a exposi\u00e7\u00e3o UV frente e verso, a XPS Crystal utiliza LEDs que n\u00e3o exigem tempo de aquecimento e emitem luz uniforme, produzindo chapas com uma consist\u00eancia incompar\u00e1vel e qualidade superior posteriormente na impress\u00e3o. A CDI Crystal XPS oferece ganhos de efici\u00eancia e qualidade, reduzindo as etapas manuais em 50%, o tempo do operador em mais de 70% e o desperd\u00edcio de chapas e tempo, com a redu\u00e7\u00e3o de erros em 50%.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cQuer\u00edamos melhorar a experi\u00eancia do nosso cliente e, ao mesmo tempo, aprimor\u00e1-la para nossos funcion\u00e1rios,\u201d disse Simon. \u201cGra\u00e7as ao sistema completo Crystal da Esko, n\u00e3o \u00e9 s\u00f3 mais simples e r\u00e1pido produzir nossas chapas flexogr\u00e1ficas \u2013 agora tamb\u00e9m temos qualidade superior na impress\u00e3o final. Usamos nosso sistema v\u00e1rias vezes ao dia, e, agora, ele \u00e9 parte essencial do nosso processo de produ\u00e7\u00e3o, especialmente com a constante redu\u00e7\u00e3o dos prazos.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m da CDI Crystal XPS, a Imprimerie Ste-Julie tamb\u00e9m investiu no&nbsp;<a href=\"https:\/\/www.esko.com\/pt\/products\/automation-engine\" rel=\"nofollow noopener\" target=\"_blank\">Automation Engine<\/a>&nbsp;da Esko, um servidor de fluxo de trabalho automatizado, como uma das ferramentas centrais em suas opera\u00e7\u00f5es. \u201cO Automation Engine importa informa\u00e7\u00f5es do software de comando,\u201d disse Simon. \u201cEnt\u00e3o, adicionamos o&nbsp;<a href=\"https:\/\/www.esko.com\/pt\/products\/pack-proof\" rel=\"nofollow noopener\" target=\"_blank\">Proof Pack<\/a>&nbsp;para nossas solu\u00e7\u00f5es de cores, a CDI e a XPS Crystal para a fabrica\u00e7\u00e3o de chapas flexogr\u00e1ficas, bem como outras ferramentas que nos permitem trabalhar com dados vari\u00e1veis e criar&nbsp;<a href=\"https:\/\/www.esko.com\/pt\/products\/studio\" rel=\"nofollow noopener\" target=\"_blank\">3D models<\/a>&nbsp;de recipientes para corre\u00e7\u00e3o de filmes termoencolh\u00edveis e v\u00e1rios produtos impressos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cGra\u00e7as a essa aquisi\u00e7\u00e3o, n\u00e3o temos mais restri\u00e7\u00f5es de velocidade e qualidade nos processos de pr\u00e9-impress\u00e3o e produ\u00e7\u00e3o\u201d.\u201d<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201cGra\u00e7as a essa aquisi\u00e7\u00e3o, n\u00e3o temos mais restri\u00e7\u00f5es de velocidade e qualidade nos processos de pr\u00e9-impress\u00e3o e produ\u00e7\u00e3o\u201d.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Simon Dumais, gerente de pr\u00e9-impress\u00e3o da Imprimerie Ste-Julie<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1000\" height=\"667\" src=\"https:\/\/dxdev.site\/induquimica\/wp-content\/uploads\/2025\/11\/imprimerie-ste-julie_4.jpg\" alt=\"\" class=\"wp-image-9371\" srcset=\"https:\/\/dxdev.site\/induquimica\/wp-content\/uploads\/2025\/11\/imprimerie-ste-julie_4.jpg 1000w, https:\/\/dxdev.site\/induquimica\/wp-content\/uploads\/2025\/11\/imprimerie-ste-julie_4-300x200.jpg 300w, https:\/\/dxdev.site\/induquimica\/wp-content\/uploads\/2025\/11\/imprimerie-ste-julie_4-768x512.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"benefits\">Os benef\u00edcios<\/h3>\n\n\n\n<h4 class=\"wp-block-heading\">Maior agilidade, maior velocidade<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cO principal benef\u00edcio que a CDI e a XPS Crystal da Esko traz para nossa empresa \u00e9 que, agora, conseguimos produzir chapas de qualidade superior com maior velocidade,\u201d disse Simon. \u201cIsso nos d\u00e1 mais agilidade para responder \u00e0 crescente expectativa dos clientes por prazos curtos inesperados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c\u00c9 importante citar que, gra\u00e7as \u00e0 tecnologia de software de alta defini\u00e7\u00e3o Pixel+ da Esko combinada com o sistema Crystal XPS, a qualidade n\u00e3o \u00e9 mais um obst\u00e1culo para a velocidade,\u201d disse ele. \u201cAl\u00e9m disso, o tempo de produ\u00e7\u00e3o das nossas chapas flexogr\u00e1ficas teve uma redu\u00e7\u00e3o de 66% em compara\u00e7\u00e3o com nosso antigo equipamento. Isso \u00e9 muito importante, porque nos permite responder mais rapidamente \u00e0s demandas dos nossos clientes ou refazer uma ou mais chapas quando a impress\u00e3o \u00e9 interrompida. Al\u00e9m disso, a possibilidade de trabalhar com chapas maiores nos permite atender com mais facilidade \u00e0 demanda pela nossa impressora de \u201d20 polegadas e, ao mesmo tempo, utilizar todas as outras impressoras, evitando interrup\u00e7\u00f5es e desperd\u00edcios.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Simon disse que a qualidade e efici\u00eancia do sistema da Esko se mostrou muito surpreendente. \u201cA consist\u00eancia dos pisos e das \u00e1reas grav\u00e1veis e a defini\u00e7\u00e3o dos pontos das nossas chapas evitam muitos desperd\u00edcios e interrup\u00e7\u00f5es de impress\u00e3o causados por chapas defeituosas,\u201d disse ele. \u201cEstamos mais do que satisfeitos! Essa tecnologia nos permite criar impress\u00f5es flexogr\u00e1ficas t\u00e3o belas quanto as digitais, ou talvez at\u00e9 mais. As cores s\u00e3o sempre vivas, e os gradientes, perfeitos!\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agora, o sistema est\u00e1 completamente operacional, ajudando a Imprimerie Ste-Julie a manter a sua promessa de concluir cada trabalho com paix\u00e3o, qualidade, foco no cliente e agilidade.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201cO tempo de produ\u00e7\u00e3o das nossa chapas flexogr\u00e1ficas teve uma redu\u00e7\u00e3o de 66% em compara\u00e7\u00e3o com nosso antigo equipamento\u201d.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Simon Dumais, gerente de pr\u00e9-impress\u00e3o da Imprimerie Ste-Julie<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" src=\"https:\/\/dxdev.site\/induquimica\/wp-content\/uploads\/2025\/11\/imprimerie-ste-julie_5.jpg\" alt=\"\" class=\"wp-image-9366\" srcset=\"https:\/\/dxdev.site\/induquimica\/wp-content\/uploads\/2025\/11\/imprimerie-ste-julie_5.jpg 1000w, https:\/\/dxdev.site\/induquimica\/wp-content\/uploads\/2025\/11\/imprimerie-ste-julie_5-300x200.jpg 300w, https:\/\/dxdev.site\/induquimica\/wp-content\/uploads\/2025\/11\/imprimerie-ste-julie_5-768x512.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>A Imprimerie Ste-Julie, empresa canadense l\u00edder do mercado de embalagens e etiquetas, procurava alavancar a produ\u00e7\u00e3o de chapas sem comprometer a qualidade da impress\u00e3o final. Com a necessidade de entregar chapas maiores em prazos reduzidos, a empresa identificou a Esko como a parceira perfeita para ajud\u00e1-los! O desafio: Velocidade, precis\u00e3o e qualidade A solu\u00e7\u00e3o: Sistema [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":9365,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_sitemap_exclude":false,"_sitemap_priority":"","_sitemap_frequency":"","_joinchat":[],"footnotes":""},"categories":[25,30],"tags":[],"class_list":["post-9364","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-case-studies","category-esko"],"_links":{"self":[{"href":"https:\/\/dxdev.site\/induquimica\/wp-json\/wp\/v2\/posts\/9364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dxdev.site\/induquimica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dxdev.site\/induquimica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dxdev.site\/induquimica\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/dxdev.site\/induquimica\/wp-json\/wp\/v2\/comments?post=9364"}],"version-history":[{"count":0,"href":"https:\/\/dxdev.site\/induquimica\/wp-json\/wp\/v2\/posts\/9364\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dxdev.site\/induquimica\/wp-json\/wp\/v2\/media\/9365"}],"wp:attachment":[{"href":"https:\/\/dxdev.site\/induquimica\/wp-json\/wp\/v2\/media?parent=9364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dxdev.site\/induquimica\/wp-json\/wp\/v2\/categories?post=9364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dxdev.site\/induquimica\/wp-json\/wp\/v2\/tags?post=9364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}