{"id":9351,"date":"2025-11-13T11:41:37","date_gmt":"2025-11-13T11:41:37","guid":{"rendered":"https:\/\/dxdev.site\/induquimica\/?p=9351"},"modified":"2025-11-13T11:41:39","modified_gmt":"2025-11-13T11:41:39","slug":"ao-eliminar-as-verificacoes-manuais-gracas-ao-artioscad-preflight-a-greif-economiza-ate-15-minutos-por-projeto","status":"publish","type":"post","link":"https:\/\/dxdev.site\/induquimica\/ao-eliminar-as-verificacoes-manuais-gracas-ao-artioscad-preflight-a-greif-economiza-ate-15-minutos-por-projeto\/","title":{"rendered":"Ao eliminar as verifica\u00e7\u00f5es manuais, gra\u00e7as ao ArtiosCAD Preflight, a Greif economiza at\u00e9 15 minutos por projeto"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Controle de qualidade aprimorado para desenhos estruturais gera efici\u00eancia e aumenta a produtividade da l\u00edder global em embalagens<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">O desafio<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Mais efici\u00eancia, menos erros e tempo de inatividade<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">A solu\u00e7\u00e3o<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Inova\u00e7\u00e3o em controle de qualidade<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Os benef\u00edcios<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Mais precis\u00e3o, maior efici\u00eancia<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Resumo de estudo de caso<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">L\u00edder global em produtos e servi\u00e7os de embalagem industrial, a miss\u00e3o da&nbsp;<a target=\"_blank\" rel=\"noreferrer noopener nofollow\" href=\"https:\/\/www.greif.com\/\">Greif<\/a>&nbsp;\u00e9 ser a empresa com o melhor servi\u00e7o de atendimento ao cliente no setor em que atua. Produzindo desde tambores de a\u00e7o, pl\u00e1stico e fibra, recipientes para mercadoria a granel at\u00e9 produtos flex\u00edveis, papel\u00e3o para embalagens, papel\u00e3o reciclado com e sem revestimento e tubos de papel\u00e3o, a Greif \u00e9 reconhecida por seu diversificado mix de produtos especializados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A empresa tamb\u00e9m fabrica acess\u00f3rios para embalagens e fornece servi\u00e7os de envase e embalagem, entre outros, para diversos setores, al\u00e9m de administrar \u00e1reas de cultura madeireira no sudeste dos Estados Unidos. A Greif desfruta de uma posi\u00e7\u00e3o estrat\u00e9gica com 290 centros operacionais em 43 pa\u00edses, servindo tanto clientes globais como regionais.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Mais efici\u00eancia, menos erros e tempo de inatividade<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A partir do Centro de Solu\u00e7\u00f5es de Embalagens da Greif, o Designer S\u00eanior Alex Salerno colabora com seus colegas de desenho estrutural. \u201cSou um usu\u00e1rio especial; trabalho exclusivamente no preparo de facas de corte para a fabrica\u00e7\u00e3o, e trabalho de perto com outros designers de embalagens do meu grupo\u201d, explica.<\/p>\n\n\n\n<figure class=\"wp-block-image alignleft size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"450\" height=\"553\" src=\"https:\/\/dxdev.site\/induquimica\/wp-content\/uploads\/2025\/11\/greif_challenge_1.jpg\" alt=\"\" class=\"wp-image-9353\" srcset=\"https:\/\/dxdev.site\/induquimica\/wp-content\/uploads\/2025\/11\/greif_challenge_1.jpg 450w, https:\/\/dxdev.site\/induquimica\/wp-content\/uploads\/2025\/11\/greif_challenge_1-244x300.jpg 244w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cFazemos um pouco de tudo, como embalagens para alimentos e bebidas, para medicamentos e autope\u00e7as, embalagens flex\u00edveis para salgadinhos. Tudo. A equipe de desenho estrutural trabalha constantemente em projetos que precisam ser colocados em pr\u00e1tica, e \u00e9 aqui que o ArtiosCAD Preflight da Esko entra em cena! Porque n\u00e3o importa o projeto em que voc\u00ea esteja trabalhando, voc\u00ea quer ter certeza de que seus arquivos est\u00e3o livres de erros.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alex explica que existem in\u00fameros erros e problemas que podem comprometer os arquivos de design. \u201cRecebemos designs em diversos formatos de arquivo e, \u00e0s vezes, existem varia\u00e7\u00f5es estruturais contr\u00e1rias aos nossos padr\u00f5es de integridade\u201d, afirma. \u201cAprendi a inspecionar as cria\u00e7\u00f5es minuciosamente, e meu trabalho \u00e9 examinar cada arquivo antes de envi\u00e1-lo para a produ\u00e7\u00e3o.<\/p>\n\n\n\n<figure class=\"wp-block-image alignright size-full\"><img decoding=\"async\" width=\"450\" height=\"253\" src=\"https:\/\/dxdev.site\/induquimica\/wp-content\/uploads\/2025\/11\/greif_customer_2-1.jpg\" alt=\"\" class=\"wp-image-9355\" srcset=\"https:\/\/dxdev.site\/induquimica\/wp-content\/uploads\/2025\/11\/greif_customer_2-1.jpg 450w, https:\/\/dxdev.site\/induquimica\/wp-content\/uploads\/2025\/11\/greif_customer_2-1-300x169.jpg 300w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Depois de analisar o projeto em si e localizar e corrigir todos os erros, a cria\u00e7\u00e3o \u00e9 integrada aos layouts, chapas de matriz, unidades de verniz e blanquetas. Ou seja, combinar todos esses elementos exige trabalho manual, o que pode consumir um tempo valioso.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alex, que j\u00e1 era usu\u00e1rio das solu\u00e7\u00f5es de software da Esko, afirma que conheceu o ArtiosCAD Preflight ao fazer upgrade para o ArtiosCAD 18.1, o que lhe concedeu acesso gratuito ao m\u00f3dulo rec\u00e9m-lan\u00e7ado.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Inova\u00e7\u00e3o em controle de qualidade<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c\u201dNossos clientes preferem trabalhar conosco porque nos dedicamos completamente a eles\u201d\u201d, afirma Alex. \u201c\u201dEstamos sempre dispon\u00edveis, 24 horas por dia, 7 dias por semana, e nosso atendimento \u00e9 inigual\u00e1vel. Nossos designers colaboram individualmente com nossos clientes, os respons\u00e1veis pelas contas e os representantes de vendas.\u201d<\/p>\n\n\n\n<figure class=\"wp-block-image alignleft size-full\"><img decoding=\"async\" width=\"450\" height=\"262\" src=\"https:\/\/dxdev.site\/induquimica\/wp-content\/uploads\/2025\/11\/greif_challenge_2.jpg\" alt=\"\" class=\"wp-image-9356\" srcset=\"https:\/\/dxdev.site\/induquimica\/wp-content\/uploads\/2025\/11\/greif_challenge_2.jpg 450w, https:\/\/dxdev.site\/induquimica\/wp-content\/uploads\/2025\/11\/greif_challenge_2-300x175.jpg 300w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c\u201dComo a satisfa\u00e7\u00e3o do cliente \u00e9 a nossa maior prioridade, \u00e9 fundamental que os nossos produtos finais sejam entregues de acordo com os padr\u00f5es de qualidade mais elevados. Portanto, esta \u00e9 a ferramenta perfeita para algu\u00e9m como eu!\u201d\u201d, refor\u00e7a Alex.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com desempenho inigual\u00e1vel em projetos CAD para embalagens e displays, o novo software ArtiosCAD Preflight da Esko aumenta a efici\u00eancia do usu\u00e1rio, economizando at\u00e9 15 minutos por projeto, eliminando as verifica\u00e7\u00f5es manuais e padronizando as revis\u00f5es do design em um mesmo grupo de usu\u00e1rios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c\u201dNormalmente, trabalhamos em milhares de projetos por ano\u201d\u201d, afirma Alex. \u201c\u201dQualquer ferramenta que possa ajudar a equipe de cria\u00e7\u00e3o a garantir precis\u00e3o m\u00e1xima traz grandes benef\u00edcios em termos de recursos.\u201d\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desenvolvido para aumentar a produtividade dos designers de embalagens estruturais nos processos de desenvolvimento de produto, prototipagem virtual e produ\u00e7\u00e3o de faca de corte, o ArtiosCAD da Esko \u00e9 uma ferramenta conceituada, com mais de 23 mil usu\u00e1rios em todo o mundo. Os princ\u00edpios de fabrica\u00e7\u00e3o mais modernos, baseados em normas da ind\u00fastria, que incluem as diretrizes da BOBST ABC, s\u00e3o validados no ArtiosCAD Preflight para assegurar que os desenhos sejam precisos e estejam prontos para produ\u00e7\u00e3o, reduzindo os ciclos repetitivos entre a cria\u00e7\u00e3o e o corte. Todos os projetos s\u00e3o inspecionados para garantir a agilidade e a precis\u00e3o de remo\u00e7\u00e3o de res\u00edduos durante o corte, e os poss\u00edveis problemas de produ\u00e7\u00e3o j\u00e1 s\u00e3o identificados na etapa de cria\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c\u201dFui o primeiro a ter acesso e a usar a ferramenta de preflight\u201d\u201d, diz Alex. \u201c\u201dN\u00e3o sabia muito a respeito do m\u00f3dulo, mas obtive acesso a ele ao instalar a vers\u00e3o mais recente do ArtiosCAD durante uma atualiza\u00e7\u00e3o geral do sistema. Logo percebi que o ArtiosCAD poderia ajudar nossos designers, e a mim mesmo, a identificar mais erros do que n\u00f3s ou qualquer outro programador encontraria normalmente.\u201d<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Mais precis\u00e3o, maior efici\u00eancia<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cO ArtiosCAD Preflight da Esko \u00e9 especialmente \u00fatil para reduzir a quantidade de erros nos arquivos de design\u201d, aponta Alex. \u201cAntes, era preciso examin\u00e1-los em busca de erros, um processo sujeito a falhas humanas. Agora, o ArtiosCAD Preflight me ajuda a criar arquivos com a m\u00e1xima perfei\u00e7\u00e3o poss\u00edvel para a produ\u00e7\u00e3o. O Preflight \u00e9 um \u2018par de olhos extra\u2019 para avaliar a qualidade.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alex conta, por exemplo, que o ArtiosCAD Preflight faz toda a diferen\u00e7a no processo de cria\u00e7\u00e3o da Greif quando usam arquivos de blanquetas de verniz com base em linhas de sangria. \u201c\u00c0s vezes as linhas de sangria n\u00e3o se conectam corretamente, e para localizar e corrigir este erro \u00e9 necess\u00e1rio fazer uma inspe\u00e7\u00e3o manual demorada, com zoom em alta resolu\u00e7\u00e3o\u201d, comenta Alex. \u201cN\u00e3o \u00e9 poss\u00edvel enxergar o erro a olho nu, mas o ArtiosCAD Preflight encontra o problema.\u201d<\/p>\n\n\n\n<figure class=\"wp-block-image alignleft size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"450\" src=\"https:\/\/dxdev.site\/induquimica\/wp-content\/uploads\/2025\/11\/greif_benefits_2.jpg\" alt=\"\" class=\"wp-image-9357\" srcset=\"https:\/\/dxdev.site\/induquimica\/wp-content\/uploads\/2025\/11\/greif_benefits_2.jpg 450w, https:\/\/dxdev.site\/induquimica\/wp-content\/uploads\/2025\/11\/greif_benefits_2-300x300.jpg 300w, https:\/\/dxdev.site\/induquimica\/wp-content\/uploads\/2025\/11\/greif_benefits_2-150x150.jpg 150w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cO ArtiosCAD Preflight me informa que a linha de sangria n\u00e3o est\u00e1 bem formada e indica onde encontrar o erro.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alex afirma que esta capacidade \u00fanica de identificar e corrigir tais erros em arquivos de desenho estrutural lhes permite economizar muito tempo em toda a cadeia de design da empresa. \u201cSe pensarmos na quantidade de pequenos erros que podem ocorrer e no tempo que seria necess\u00e1rio para corrigi-los, os benef\u00edcios do ArtiosCAD Preflight se tornam evidentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agora, antes de iniciar a produ\u00e7\u00e3o, posso examinar um arquivo minuciosamente muito mais r\u00e1pido. Localizar, sinalizar e corrigir os problemas de cria\u00e7\u00e3o nesta etapa economiza tempo e evita desperd\u00edcios mais \u00e0 frente, tornando todo o processo mais eficiente. Al\u00e9m disso, quando envio o arquivo pronto e atualizado, ele cumpre com os nossos padr\u00f5es elevados de qualidade. Os designers podem inclu\u00ed-lo diretamente em suas bibliotecas, economizando ainda mais tempo.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">At\u00e9 o fim de 2020, Alex espera que todos os membros da equipe de design tenham a atualiza\u00e7\u00e3o do ArtiosCAD 18.1 e seu pr\u00f3prio acesso ao m\u00f3dulo do ArtiosCAD Preflight. \u201cEspero que eles usem o m\u00f3dulo tanto quanto eu\u201d, afirma. \u201cIsso simplificar\u00e1 ainda mais meu trabalho!\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Controle de qualidade aprimorado para desenhos estruturais gera efici\u00eancia e aumenta a produtividade da l\u00edder global em embalagens O desafio Mais efici\u00eancia, menos erros e tempo de inatividade A solu\u00e7\u00e3o Inova\u00e7\u00e3o em controle de qualidade Os benef\u00edcios Mais precis\u00e3o, maior efici\u00eancia Resumo de estudo de caso L\u00edder global em produtos e servi\u00e7os de embalagem industrial, [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":9352,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_sitemap_exclude":false,"_sitemap_priority":"","_sitemap_frequency":"","_joinchat":[],"footnotes":""},"categories":[25,30],"tags":[],"class_list":["post-9351","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-case-studies","category-esko"],"_links":{"self":[{"href":"https:\/\/dxdev.site\/induquimica\/wp-json\/wp\/v2\/posts\/9351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dxdev.site\/induquimica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dxdev.site\/induquimica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dxdev.site\/induquimica\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/dxdev.site\/induquimica\/wp-json\/wp\/v2\/comments?post=9351"}],"version-history":[{"count":0,"href":"https:\/\/dxdev.site\/induquimica\/wp-json\/wp\/v2\/posts\/9351\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dxdev.site\/induquimica\/wp-json\/wp\/v2\/media\/9352"}],"wp:attachment":[{"href":"https:\/\/dxdev.site\/induquimica\/wp-json\/wp\/v2\/media?parent=9351"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dxdev.site\/induquimica\/wp-json\/wp\/v2\/categories?post=9351"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dxdev.site\/induquimica\/wp-json\/wp\/v2\/tags?post=9351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}